{"id":2670,"date":"2025-04-06T01:27:12","date_gmt":"2025-04-06T01:27:12","guid":{"rendered":"https:\/\/allroblox.com\/game\/murderers-vs-sheriffs-duels\/"},"modified":"2025-04-06T01:27:14","modified_gmt":"2025-04-06T01:27:14","slug":"murderers-vs-sheriffs-duels","status":"publish","type":"game","link":"https:\/\/allroblox.com\/ko\/game\/murderers-vs-sheriffs-duels\/","title":{"rendered":"\uc554\uc0b4\uc790 VS \ubcf4\uc548\uad00 \ub4c0\uc5d8"},"content":{"rendered":"<p class=\"translation-block\">\uc561\uc158 \ubc0f \uc804\ub7b5 \uac8c\uc784\uc744 \uc88b\uc544\ud558\ub294 Roblox \ud32c\uc774\ub77c\uba74 \"Assassinos VS Xerifes Duelos\"(\uc601\uc5b4\ub85c \"Murderers VS Sheriffs Duels\"\ub85c \uc54c\ub824\uc9d0)\ub294 \uc8fc\ubaa9\ud560 \uac00\uce58\uac00 \uc788\ub294 \uacbd\ud5d8\uc785\ub2c8\ub2e4. Red21 Games \uc2a4\ud29c\ub514\uc624\uc5d0\uc11c \uc81c\uc791\ud55c \uc774 \uac8c\uc784\uc740 1v1\uc640 \uac19\uc740 \uc194\ub85c \ubaa8\ub4dc\uc640 2v2, 3v3, 4v4\uc640 \uac19\uc740 \ud300 \ubaa8\ub4dc\uc5d0\uc11c \uce58\uc5f4\ud55c \uc804\ud22c\ub97c \uc81c\uacf5\ud569\ub2c8\ub2e4. \uc120\uc218\ub4e4\uc740 \uc544\ub4dc\ub808\ub0a0\ub9b0\uc774 \ub118\uce58\ub294 \uacb0\ud22c\uc5d0\uc11c \ubc18\ub300 \uc5ed\ud560\uc744 \ub9e1\uc2b5\ub2c8\ub2e4. \ub3c5\ud2b9\ud55c \uba54\ucee4\ub2c8\uc998, \uc0ac\uc6a9\uc790 \uc815\uc758 \uac00\ub2a5\ud55c \uc2a4\ud0a8 \ubc0f \ud65c\ubc1c\ud55c \ucee4\ubba4\ub2c8\ud2f0\uc640 \ud568\uaed8 \uacbd\ud5d8\uc740 \uacbd\uc7c1\uc801\uc778 \uc7ac\ubbf8\uc758 \uc2dc\uac04\uc744 \uc57d\uc18d\ud569\ub2c8\ub2e4.<\/p>\n<h2>\uc554\uc0b4\uc790 \ub300 \ubcf4\uc548\uad00 \uacb0\ud22c \ubc29\ubc95<\/h2>\n<p class=\"translation-block\">\u201cAssassinos VS Xerifes Duelos\u201d\uc758 \uc8fc\uc694 \ubaa9\ud45c\ub294 \uac04\ub2e8\ud569\ub2c8\ub2e4: \uc554\uc0b4\uc790\ub294 \ubd99\uc7a1\ud788\uae30 \uc804\uc5d0 \ubcf4\uc548\uad00\uc744 \uc81c\uac70\ud574\uc57c \ud558\uace0, \ubcf4\uc548\uad00\uc740 \ubc94\uc8c4\uc790\ub97c \ubb34\ub825\ud654\ud558\uc5ec \uc9c8\uc11c\ub97c \uc720\uc9c0\ud574\uc57c \ud569\ub2c8\ub2e4. \uc774 \uac8c\uc784\uc740 \uac01\uae30 \ub2e4\ub978 \uaddc\uce59\uacfc \uc804\ub7b5\uc774 \uc788\ub294 \uc5ec\ub7ec \ubaa8\ub4dc\ub97c \uc81c\uacf5\ud569\ub2c8\ub2e4.<\/p>\n<h3>\uae30\ubcf8 \uc870\uc791<\/h3>\n<p class=\"translation-block\">\uc870\uc791\uc774 \uc9c1\uad00\uc801\uc774\uba70 Roblox\uc758 \ub2e4\ub978 \uac8c\uc784\ub4e4\uacfc \ub3d9\uc77c\ud55c \ud328\ud134\uc744 \ub530\ub985\ub2c8\ub2e4:<\/p>\n<ul>\n<li>\uc774\ub3d9: WASD \ud0a4<\/li>\n<li>\uc2a4\ud398\uc774\uc2a4\ubc14<\/li>\n<li>\uacf5\uaca9: \ub9c8\uc6b0\uc2a4 \uc67c\ucabd \ubc84\ud2bc<\/li>\n<li>\ub9c8\uc6b0\uc2a4 \uc624\ub978\ucabd \ubc84\ud2bc \ud074\ub9ad(\uc7a5\uac70\ub9ac \ubb34\uae30\uc6a9)<\/li>\n<li>\ud2b9\uc218 \ub2a5\ub825: \uc22b\uc790 \ud0a4 \ub610\ub294 Q\/E, \uc124\uc815\uc5d0 \ub530\ub77c \ub2e4\ub984<\/li>\n<\/ul>\n<h3>\ucd08\ubcf4\uc790\ub97c \uc704\ud55c \ud29c\ud1a0\ub9ac\uc5bc<\/h3>\n<p class=\"translation-block\">\uac8c\uc784\uc5d0 \ucc98\uc74c\uc774\ub77c\uba74 \ud6c8\ub828 \ubaa8\ub4dc\ub97c \ud0d0\uc0c9\ud558\uba74\uc11c \uba54\ucee4\ub2c8\uc998\uc5d0 \uc775\uc219\ud574\uc9c0\ub294 \uac83\ubd80\ud130 \uc2dc\uc791\ud558\uc138\uc694. \uce7c\uacfc \ub9ac\ubcfc\ubc84 \uc0ac\uc6a9\uc744 \uc5f0\uc2b5\ud558\uace0, \uc228\ub294 \ubc95\uc744 \ubc30\uc6b0\uba70 \uac01 \ud074\ub798\uc2a4\uc758 \ud2b9\uc218 \ub2a5\ub825\uc744 \uc775\ud788\uc138\uc694. \ud300 \ub0b4 \uc18c\ud1b5\uc740 \ud544\uc218\uc801\uc774\uba70, \ud2b9\ud788 2v2 \ub610\ub294 3v3 \ubaa8\ub4dc\uc5d0\uc11c \uc911\uc694\ud569\ub2c8\ub2e4.<\/p>\n<h2>\ubb34\ub8cc \uc544\uc774\ud15c \ubc0f \ucf54\ub4dc - \uc554\uc0b4\uc790 \ub300 \ubcf4\uc548\uad00 \uacb0\ud22c<\/h2>\n<p class=\"translation-block\">\ub85c\ube14\ub85d\uc2a4\uc758 \ub9ce\uc740 \uacbd\ud5d8\uacfc \ub9c8\ucc2c\uac00\uc9c0\ub85c \u201c\uc0b4\uc778\uc790 VS \ubcf4\uc548\uad00 \ub4c0\uc5d8\u201d\uc740 \ub3c5\uc810 \uc2a4\ud0a8, \ubcf4\uc11d \ub610\ub294 \uc784\uc2dc \ubd80\uc2a4\ud2b8\uc640 \uac19\uc740 \ubcf4\uc0c1\uc73c\ub85c \uad50\ud658\ud560 \uc218 \uc788\ub294 \ud504\ub85c\ubaa8\uc158 \ucf54\ub4dc\ub97c \uc81c\uacf5\ud569\ub2c8\ub2e4. \uc774\ub7ec\ud55c \ucf54\ub4dc\ub294 \uc885\uc885 \uac8c\uc784\uc758 \uacf5\uc2dd \uc18c\uc15c \ubbf8\ub514\uc5b4 \ub610\ub294 \ud2b9\ubcc4 \uc774\ubca4\ud2b8\uc5d0\uc11c \uacf5\uac1c\ub429\ub2c8\ub2e4.<\/p>\n<p class=\"translation-block\">\uc5ec\uae30 \uba87 \uac00\uc9c0 \uc720\ud6a8\ud55c \ucf54\ub4dc\uac00 \uc788\uc2b5\ub2c8\ub2e4(\ud56d\uc0c1 \uc720\ud6a8 \uae30\uac04\uc744 \ud655\uc778\ud558\uc138\uc694):<\/p>\n<ul>\n<li>DUELOS2024 \u2013 \ud76c\uadc0\ud55c \uce7c \uc2a4\ud0a8\uc744 \uc5bb\uae30 \uc704\ud55c \uad6c\uc870<\/li>\n<li>RED21GAMES \u2013 \ud2b9\ubcc4\ud55c \ub9ac\ubcfc\ubc84\ub97c \uc7a0\uae08 \ud574\uc81c\ud558\uc2ed\uc2dc\uc624.<\/li>\n<li>\ube44\ud1a0\ub9ac\uc544\ud30c\uc2e4 \u2013 \uc5c5\uadf8\ub808\uc774\ub4dc\ub97c \uc704\ud55c \ucd94\uac00 \ubcf4\uc11d\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4.<\/li>\n<\/ul>\n<p class=\"translation-block\">\uac8c\uc784 \uba54\ub274\ub97c \uc5f4\uace0 \"\ucf54\ub4dc\" \uc635\uc158\uc744 \ud074\ub9ad\ud55c \ub2e4\uc74c \uc870\ud569\uc744 \uc785\ub825\ud558\uae30\ub9cc \ud558\uba74 \ub429\ub2c8\ub2e4. \uc0c8\ub85c\uc6b4 \ucf54\ub4dc\uac00 \uc815\uae30\uc801\uc73c\ub85c \ucd9c\uc2dc\ub418\ubbc0\ub85c \uc5c5\ub370\uc774\ud2b8\uc5d0 \uc8fc\uc758\ud558\uc138\uc694.<\/p>\n<h2>\uac8c\uc784\uc744 \uc815\ubcf5\ud558\uae30 \uc704\ud55c \ud301<\/h2>\n<p class=\"translation-block\">\u201cAssassinos VS Xerifes Duelos\u201d\uc5d0\uc11c \ub208\uc5d0 \ub744\uace0 \uc2f6\ub2e4\uba74 \uba87 \uac00\uc9c0 \uc804\ub7b5\uc774 \ucc28\uc774\ub97c \ub9cc\ub4e4 \uc218 \uc788\uc2b5\ub2c8\ub2e4:<\/p>\n<ul>\n<li>\ud658\uacbd\uc744 \ub2f9\uc2e0\uc758 \uc720\ub9ac\ud558\uac8c \uc0ac\uc6a9\ud558\uc138\uc694: \uc228\uaca8\uc9c4 \uc7a5\uc18c\uc640 \ub300\uccb4 \uacbd\ub85c\ub294 \uc801\ub4e4\uc744 \ub180\ub77c\uac8c \ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/li>\n<li>\uacf5\uaca9 \ud328\ud134\uc744 \ubc30\uc6b0\uc138\uc694: \uac01 \ubb34\uae30\ub294 \ub2e4\ub978 \uc7ac\uc7a5\uc804 \uc2dc\uac04\uacfc \uc0ac\uac70\ub9ac\ub97c \uac00\uc9c0\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/li>\n<li>\ud300 \ud50c\ub808\uc774\ub97c \ud558\uc138\uc694: \ub3d9\ub9f9\ub4e4\uacfc \ud611\ub825\ud558\uc5ec \uc801\uc744 \uce21\uba74\uc5d0\uc11c \uacf5\uaca9\ud558\uc138\uc694.<\/li>\n<li>\uae30\uc220\uc5d0 \ud22c\uc790\ud558\uc138\uc694: \uac8c\uc784 \uc2a4\ud0c0\uc77c\uc5d0 \ub9de\ub294 \uc5c5\uadf8\ub808\uc774\ub4dc\ub97c \uc6b0\uc120\uc801\uc73c\ub85c \uace0\ub824\ud558\uc138\uc694.<\/li>\n<\/ul>\n<p class=\"translation-block\">\ubcf4\uc11d\uc774\ub098 \ud1b5\uacc4 \uc791\uc5c5\uc740 \uae08\uc9c0\ub418\uc5b4 \uc788\uc73c\uba70 \uc601\uad6c \ucc28\ub2e8\uc758 \uc6d0\uc778\uc774 \ub420 \uc218 \uc788\uc74c\uc744 \uae30\uc5b5\ud558\uc138\uc694. \ubc1c\uc804\ud558\ub294 \uac00\uc7a5 \uc88b\uc740 \ubc29\ubc95\uc740 \uc5f0\uc2b5\uacfc \uc804\ub7b5\uc744 \ud1b5\ud574\uc11c\uc785\ub2c8\ub2e4.<\/p>\n<h2>\uac8c\uc784\uc758 \ud638\uae30\uc2ec\uacfc \ube44\ubc00<\/h2>\n<p class=\"translation-block\">\u201cAssassinos VS Xerifes Duelos\u201d\uc740 \uba87\uba87 \ud50c\ub808\uc774\uc5b4\uac00 \uc54c\uace0 \uc788\ub294 \uba87 \uac00\uc9c0 \ud765\ubbf8\ub85c\uc6b4 \ube44\ubc00\uc744 \uc228\uae30\uace0 \uc788\uc2b5\ub2c8\ub2e4:<\/p>\n<ul>\n<li>\ud2b9\uc815 \ub3c4\uc804\uc744 \uc644\ub8cc\ud574\uc57c\ub9cc \ud574\uc81c\ud560 \uc218 \uc788\ub294 \ube44\ubc00 \uc2a4\ud0a8\uc774 \uc788\uc73c\uba70, \uc608\ub97c \ub4e4\uc5b4 100\uacbd\uae30\ub97c \uc774\uae30\uac70\ub098 \ub192\uc740 \ub7ad\ud06c\uc5d0 \ub3c4\ub2ec\ud574\uc57c \ud569\ub2c8\ub2e4.<\/li>\n<li>\uc77c\ubd80 \uc9c0\ub3c4\ub294 \ud2b9\uc218\ud55c \uc2dc\uc57c\ub098 \ud0c8\ucd9c \uacbd\ub85c\uc640 \uac19\uc740 \uc804\uc220\uc801 \uc774\uc810\uc744 \uc81c\uacf5\ud558\ub294 \uc228\uaca8\uc9c4 \uc9c0\uc5ed\uc744 \ud3ec\ud568\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<\/li>\n<li>\uac8c\uc784\uc740 \uc774\ubbf8 Roblox\uc758 \ub2e4\ub978 \ucc3d\uc791\uc790\ub4e4\uacfc \ud2b9\ubcc4\ud55c \ud611\uc5c5\uc744 \ud588\uc73c\uba70, \ud55c\uc815 \uc2dc\uac04 \ub3d9\uc548 \ud14c\ub9c8 \uc544\uc774\ud15c\uc744 \ucd94\uac00\ud588\uc2b5\ub2c8\ub2e4.<\/li>\n<\/ul>\n<p class=\"translation-block\">\ub610\ud55c \uac1c\ubc1c\uc790\ub4e4\uc740 \ubb34\uae30\uc640 \ubc30\uacbd \ub514\uc790\uc778\uc5d0 \uc11c\ubd80 \uc601\ud654\uc640 \uace0\uc804 \uac8c\uc784\uc5d0 \ub300\ud55c \ucc38\uace0 \uc790\ub8cc\ub97c \ucd94\uac00\ud558\ub294 \uacbd\uc6b0\uac00 \ub9ce\uc2b5\ub2c8\ub2e4.<\/p>\n<h2>\uc790\uc8fc \ubb3b\ub294 \uc9c8\ubb38<\/h2>\n<h3>\uac8c\uc784\uc5d0\uc11c \uc2a4\ud0a8\uc744 \uc5b4\ub5bb\uac8c \uad50\ud658\ud558\ub098\uc694?<\/h3>\n<p class=\"translation-block\">\ubb34\uae30\ub97c \uac1c\uc778\ud654\ud558\ub824\uba74 \uc778\ubca4\ud1a0\ub9ac \uba54\ub274\uc5d0 \uc811\uc18d\ud558\uace0 \"\uc2a4\ud0a8\" \uc635\uc158\uc744 \uc120\ud0dd\ud558\uc138\uc694. \uac70\uae30\uc11c \ud574\uc81c\ub41c \ud56d\ubaa9\uc774\ub098 \ucf54\ub4dc\ub85c \ud68d\ub4dd\ud55c \ud56d\ubaa9\uc744 \uc7a5\ucc29\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc77c\ubd80 \uc2a4\ud0a8\uc740 \ub2e4\ub978 \ud50c\ub808\uc774\uc5b4\uc640 \uac70\ub798\ud560 \uc218\ub3c4 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<h3>\ud300\uc73c\ub85c \ud50c\ub808\uc774\ud558\uae30 \uc704\ud55c \uc694\uad6c\uc0ac\ud56d\uc740 \ubb34\uc5c7\uc778\uac00\uc694?<\/h3>\n<p class=\"translation-block\">\ud300 \ubaa8\ub4dc(2v2, 3v3, 4v4)\uc5d0\uc11c\ub294 \ud50c\ub808\uc774\uc5b4\uac00 \ucd5c\uc18c \uc218\uc900\uc744 \uac16\ucdb0\uc57c \ud558\uba70, \uc77c\ubc18\uc801\uc73c\ub85c 5 \uc218\uc900 \uc774\uc0c1\uc774\uc5b4\uc57c \ud569\ub2c8\ub2e4. \uc774\ub294 \ubaa8\ub4e0 \ud50c\ub808\uc774\uc5b4\uac00 \ubcf4\ub2e4 \uacbd\uc7c1\uc801\uc778 \uacbd\uae30\ub97c \uce58\ub974\uae30 \uc804\uc5d0 \uc77c\uc815\ud55c \uacbd\ud5d8\uc744 \uac16\ucd94\ub3c4\ub85d \ubcf4\uc7a5\ud569\ub2c8\ub2e4.<\/p>\n<h2>\ucd5c\uadfc \uc774\ubca4\ud2b8 \ubc0f \uc5c5\ub370\uc774\ud2b8<\/h2>\n<p class=\"translation-block\">\u201cAssassinos VS Xerifes Duelos\u201d\uc758 \uac1c\ubc1c\uc790\ub4e4\uc740 \uc815\uae30\uc801\uc778 \uc5c5\ub370\uc774\ud2b8\ub85c \uac8c\uc784\uc744 \uc2e0\uc120\ud558\uac8c \uc720\uc9c0\ud569\ub2c8\ub2e4. \ucd5c\uadfc\uc5d0\ub294 \ub3c4\uc2dc \ud658\uacbd\uc5d0\uc11c \uc601\uac10\uc744 \ubc1b\uc740 \uc0c8\ub85c\uc6b4 \ub9f5\uc774 \ucd94\uac00\ub418\uc5b4 \uacbd\uae30\uc5d0\uc11c \ub354 \ub9ce\uc740 \ub2e4\uc591\uc131\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4. \ub610\ud55c, \uacc4\uc808 \uc774\ubca4\ud2b8\ub294 \ud06c\ub9ac\uc2a4\ub9c8\uc2a4\ub098 \ud560\ub85c\uc708\uacfc \uac19\uc740 \ud14c\ub9c8\uc758 \uc2a4\ud0a8\uacfc \uac19\uc740 \ub3c5\uc810 \ubcf4\uc0c1\uc744 \uac00\uc838\uc635\ub2c8\ub2e4.<\/p>\n<p class=\"translation-block\">\uc0c8\ub85c\uc6b4 \uc18c\uc2dd\uc744 \ub530\ub77c\uc7a1\uc73c\ub824\uba74 Red21 Games\uc758 \uacf5\uc2dd \uac1c\ubc1c \ud3ec\ub7fc\uc774\ub098 \uc18c\uc15c \ubbf8\ub514\uc5b4\ub97c \ud314\ub85c\uc6b0\ud558\ub294 \uac83\uc774 \uc88b\uc2b5\ub2c8\ub2e4. \ub9ce\uc740 \ubcc0\ud654\uac00 \ucee4\ubba4\ub2c8\ud2f0\uc758 \ud53c\ub4dc\ubc31\uc744 \ubc14\ud0d5\uc73c\ub85c \uc774\ub8e8\uc5b4\uc9c0\uae30 \ub54c\ubb38\uc5d0, \ud50c\ub808\uc774\uc5b4\ub85c\uc11c\uc758 \ub2f9\uc2e0\uc758 \uc758\uacac\uc774 \uac8c\uc784\uc758 \ubbf8\ub798\uc5d0 \uc601\ud5a5\uc744 \ubbf8\uce60 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\n<p class=\"translation-block\">\u201c\uc554\uc0b4\uc790 \ub300 \ubcf4\uc548\uad00 \uacb0\ud22c\u201d\ub97c \uc544\uc9c1 \uacbd\ud5d8\ud558\uc9c0 \uc54a\uc558\ub2e4\uba74, \uc9c0\uae08\uc774 \uc774 \uaca9\ub82c\ud55c \uacb0\ud22c\uc640 \uc804\ub7b5\uc758 \uc138\uacc4\uc5d0 \ub6f0\uc5b4\ub4e4 \uc2dc\uac04\uc785\ub2c8\ub2e4. \ub2e4\uc591\ud55c \ubaa8\ub4dc, \uae4a\uc774 \uc788\ub294 \ucee4\uc2a4\ud130\ub9c8\uc774\uc9d5, \uc911\ub3c5\uc131 \uc788\ub294 \uac8c\uc784 \ud50c\ub808\uc774\ub85c \uc778\ud574 \uc774 \uacbd\ud5d8\uc774 Roblox \ud32c\ub4e4 \uc0ac\uc774\uc5d0\uc11c \uc5ec\uc804\ud788 \uc778\uae30\ub97c \ub044\ub294 \uc774\uc720\ub97c \uc27d\uac8c \uc774\ud574\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>","protected":false},"featured_media":2671,"template":"","meta":{"_acf_changed":false},"class_list":["post-2670","game","type-game","status-publish","has-post-thumbnail","hentry","infinite-scroll-item"],"acf":[],"meta_box":[],"_links":{"self":[{"href":"https:\/\/allroblox.com\/ko\/wp-json\/wp\/v2\/game\/2670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allroblox.com\/ko\/wp-json\/wp\/v2\/game"}],"about":[{"href":"https:\/\/allroblox.com\/ko\/wp-json\/wp\/v2\/types\/game"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allroblox.com\/ko\/wp-json\/wp\/v2\/media\/2671"}],"wp:attachment":[{"href":"https:\/\/allroblox.com\/ko\/wp-json\/wp\/v2\/media?parent=2670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}